{"id":4530,"date":"2018-06-15T14:05:46","date_gmt":"2018-06-15T18:05:46","guid":{"rendered":"https:\/\/hgh.ca\/?p=4530"},"modified":"2018-06-15T14:05:46","modified_gmt":"2018-06-15T18:05:46","slug":"lhgh-lance-un-nouveau-programme-de-therapie-respiratoire","status":"publish","type":"post","link":"https:\/\/hgh.ca\/fr\/lhgh-lance-un-nouveau-programme-de-therapie-respiratoire\/","title":{"rendered":"L&rsquo;HGH lance un nouveau programme de th\u00e9rapie respiratoire"},"content":{"rendered":"<p><strong>COMMUNIQU\u00c9 DE PRESSE<\/strong><\/p>\n<p>HAWKESBURY \u2014 Le lundi 18 juin, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) lance un nouveau Programme de th\u00e9rapie respiratoire complet. Gr\u00e2ce \u00e0 ce programme, les adultes et les enfants atteints de troubles respiratoires, d\u2019allergies, d\u2019infections respiratoires ou de maladies pulmonaires chroniques auront maintenant acc\u00e8s \u00e0 des consultations, des examens diagnostiques et des traitements en consultation externe \u00e0 l\u2019HGH.<\/p>\n<p>Le Programme de th\u00e9rapie respiratoire compte plusieurs professionnels de la sant\u00e9, dont Dr Benson Wong, pneumologue, un sp\u00e9cialiste en m\u00e9decine interne ainsi qu\u2019un th\u00e9rapeute et \u00e9ducateur respiratoire. Le programme est offert au campus principal de l\u2019HGH dans le nouveau Bloc B d\u00e9di\u00e9 aux soins ambulatoires et comprend un laboratoire pour les tests de la fonction pulmonaire. Les patients doivent avoir une requ\u00eate m\u00e9dicale de leur m\u00e9decin pour obtenir un rendez-vous.<\/p>\n<h2>Faits importants<\/h2>\n<p>Le Programme de th\u00e9rapie respiratoire comprend les volets suivants :<\/p>\n<ul>\n<li>Consultations m\u00e9dicales et suivis<\/li>\n<li>Tests complets de la fonction pulmonaire\n<ul>\n<li>Spirom\u00e9trie<\/li>\n<li>Capacit\u00e9 de diffusion pulmonaire<\/li>\n<li>Pl\u00e9thysmographie pulmonaire<\/li>\n<li>Provocation bronchique<\/li>\n<li>Saturation \u00e0 l\u2019effort\/Gaz art\u00e9riels<\/li>\n<\/ul>\n<\/li>\n<li>Ateliers \u00e9ducatifs individuels et en groupes pour la gestion des maladies<\/li>\n<li>Conseils pour l\u2019abandon du tabac<\/li>\n<li>R\u00e9adaptation pulmonaire pour am\u00e9liorer la qualit\u00e9 de vie des patients<\/li>\n<\/ul>\n<p>Pour en savoir davantage, visitez la page <a href=\"https:\/\/hgh.ca\/fr\/programmes-services\/programme-de-therapie-respiratoire\/\">Programme de th\u00e9rapie respiratoire<\/a>.<\/p>\n<h2>Citations<\/h2>\n<p>\u00ab\u2009Gr\u00e2ce au projet de r\u00e9am\u00e9nagement de l\u2019HGH, nous avons maintenant un nouveau laboratoire de la fonction pulmonaire qui nous permet d\u2019offrir ce Programme de th\u00e9rapie respiratoire complet \u00e0 nos patients. C\u2019est un beau compl\u00e9ment aux installations du Bloc B ouvert depuis janvier dernier et d\u00e9di\u00e9 aux soins ambulatoires. Nous venons de franchir une autre \u00e9tape dans notre transformation en un h\u00f4pital r\u00e9gional \u00e0 service complet.\u2009\u00bb<br \/>\n&#8211;<strong>Fran\u00e7ois Bertrand<\/strong><br \/>\nPr\u00e9sident du conseil d\u2019administration<\/p>\n<p>\u00ab\u2009Ces nouveaux \u00e9quipements m\u00e9dicaux et technologies de pointe nous rapprochent de notre objectif de devenir un h\u00f4pital mod\u00e8le en Ontario d\u2019ici 2020. L\u2019innovation est au c\u0153ur de notre d\u00e9veloppement. Je remercie les diff\u00e9rentes \u00e9quipes de travail qui ont planifi\u00e9 ce nouveau programme et recrut\u00e9 les professionnels de la sant\u00e9 afin d\u2019offrir de nouveaux services sp\u00e9cialis\u00e9s \u00e0 nos patients.\u2009\u00bb<br \/>\n&#8211;<strong>Marc LeBoutillier<\/strong><br \/>\nDirecteur g\u00e9n\u00e9ral<\/p>\n<p>\u00ab\u2009Les services de consultation et les suivis pour la gestion des maladies pulmonaires offerts par Dr Wong seront vraiment un atout pour les patients de la r\u00e9gion et leur permettront d\u2019obtenir des soins sp\u00e9cialis\u00e9s, plus pr\u00e8s du domicile. Ces soins et ces tests perfectionn\u00e9s permettront \u00e9galement de diminuer ou m\u00eame de pr\u00e9venir les admissions de patients \u00e0 l\u2019h\u00f4pital.\u2009\u00bb<br \/>\n&#8211;<strong>Dre Julie Maranda<\/strong><br \/>\nM\u00e9decin-chef<\/p>\n<h2>Information<\/h2>\n<p>Pour plus d\u2019information au sujet du programme ou demandes d&rsquo;entrevues, veuillez communiquer avec :<br \/>\nJulie Leroux<br \/>\nCoordonnatrice des communications<br \/>\nRessources humaines et Relations communautaires<br \/>\nH\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district<br \/>\nT\u00e9l\u00e9phone : 613-632-1111, poste 61013<br \/>\nCourriel : jleroux@hgh.ca<\/p>\n","protected":false},"excerpt":{"rendered":"COMMUNIQU\u00c9 DE PRESSE HAWKESBURY \u2014 Le lundi 18 juin, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) lance un nouveau Programme de th\u00e9rapie respiratoire complet. Gr\u00e2ce \u00e0 ce programme, les adultes et les enfants atteints de troubles respiratoires, d\u2019allergies, d\u2019infections respiratoires ou de maladies pulmonaires chroniques auront maintenant acc\u00e8s \u00e0 des consultations, des examens diagnostiques et&#8230; <a class=\"btn btn--primary\" href=\"https:\/\/hgh.ca\/fr\/lhgh-lance-un-nouveau-programme-de-therapie-respiratoire\/\">Acc\u00e9der l&rsquo;article<\/a>","protected":false},"author":2,"featured_media":4528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hgh.ca\/fr\/hgh-launches-a-new-respiratory-therapy-program\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital\" \/>\n<meta property=\"og:description\" content=\"COMMUNIQU\u00c9 DE PRESSE HAWKESBURY \u2014 Le lundi 18 juin, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) lance un nouveau Programme de th\u00e9rapie respiratoire complet. Gr\u00e2ce \u00e0 ce programme, les adultes et les enfants atteints de troubles respiratoires, d\u2019allergies, d\u2019infections respiratoires ou de maladies pulmonaires chroniques auront maintenant acc\u00e8s \u00e0 des consultations, des examens diagnostiques et... Acc\u00e9der l&#039;article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/\" \/>\n<meta property=\"og:site_name\" content=\"Hawkesbury General Hospital\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-15T18:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julie Leroux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julie Leroux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/\",\"url\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/\",\"name\":\"L'HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital\",\"isPartOf\":{\"@id\":\"https:\/\/hgh.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png\",\"datePublished\":\"2018-06-15T18:05:46+00:00\",\"dateModified\":\"2018-06-15T18:05:46+00:00\",\"author\":{\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage\",\"url\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png\",\"contentUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png\",\"width\":300,\"height\":250,\"caption\":\"L'HGH ouvre un nouveau service de th\u00e9rapie respiratoire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hgh.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;HGH lance un nouveau programme de th\u00e9rapie respiratoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hgh.ca\/#website\",\"url\":\"https:\/\/hgh.ca\/\",\"name\":\"Hawkesbury General Hospital\",\"description\":\"Compassion, Innovation, Excellence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hgh.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\",\"name\":\"Julie Leroux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"caption\":\"Julie Leroux\"},\"url\":\"https:\/\/hgh.ca\/fr\/author\/jleroux\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hgh.ca\/fr\/hgh-launches-a-new-respiratory-therapy-program\/","og_locale":"fr_FR","og_type":"article","og_title":"L'HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital","og_description":"COMMUNIQU\u00c9 DE PRESSE HAWKESBURY \u2014 Le lundi 18 juin, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) lance un nouveau Programme de th\u00e9rapie respiratoire complet. Gr\u00e2ce \u00e0 ce programme, les adultes et les enfants atteints de troubles respiratoires, d\u2019allergies, d\u2019infections respiratoires ou de maladies pulmonaires chroniques auront maintenant acc\u00e8s \u00e0 des consultations, des examens diagnostiques et... Acc\u00e9der l'article","og_url":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/","og_site_name":"Hawkesbury General Hospital","article_published_time":"2018-06-15T18:05:46+00:00","og_image":[{"width":300,"height":250,"url":"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png","type":"image\/png"}],"author":"Julie Leroux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julie Leroux","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/","url":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/","name":"L'HGH lance un nouveau programme de th\u00e9rapie respiratoire - Hawkesbury General Hospital","isPartOf":{"@id":"https:\/\/hgh.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage"},"image":{"@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage"},"thumbnailUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png","datePublished":"2018-06-15T18:05:46+00:00","dateModified":"2018-06-15T18:05:46+00:00","author":{"@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4"},"breadcrumb":{"@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#primaryimage","url":"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png","contentUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2018\/06\/Respiratory-Therapy-300x250.png","width":300,"height":250,"caption":"L'HGH ouvre un nouveau service de th\u00e9rapie respiratoire"},{"@type":"BreadcrumbList","@id":"https:\/\/hgh.ca\/hgh-launches-a-new-respiratory-therapy-program\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hgh.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;HGH lance un nouveau programme de th\u00e9rapie respiratoire"}]},{"@type":"WebSite","@id":"https:\/\/hgh.ca\/#website","url":"https:\/\/hgh.ca\/","name":"Hawkesbury General Hospital","description":"Compassion, Innovation, Excellence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hgh.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4","name":"Julie Leroux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","caption":"Julie Leroux"},"url":"https:\/\/hgh.ca\/fr\/author\/jleroux\/"}]}},"_links":{"self":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/4530\/"}],"collection":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/users\/2\/"}],"replies":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/comments\/?post=4530"}],"version-history":[{"count":3,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/4530\/revisions\/"}],"predecessor-version":[{"id":4533,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/4530\/revisions\/4533\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/4528\/"}],"wp:attachment":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/?parent=4530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/categories\/?post=4530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/tags\/?post=4530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}