{"id":6832,"date":"2020-11-23T09:19:03","date_gmt":"2020-11-23T14:19:03","guid":{"rendered":"https:\/\/hgh.ca\/?p=6832"},"modified":"2020-12-14T14:43:15","modified_gmt":"2020-12-14T19:43:15","slug":"nouvelle-clinique-de-counseling-sans-rendez-vous","status":"publish","type":"post","link":"https:\/\/hgh.ca\/fr\/nouvelle-clinique-de-counseling-sans-rendez-vous\/","title":{"rendered":"Nouvelle clinique de counseling sans rendez-vous"},"content":{"rendered":"<p class=\"lead\">Le d\u00e9partement de Sant\u00e9 mentale et toxicomanie de l\u2019HGH offre maintenant un acc\u00e8s simple et rapide \u00e0 des services de counseling sans rendez-vous.<\/p>\n<p>Les personnes \u00e2g\u00e9es de 16 ans ou plus peuvent obtenir une consultation unique avec un psychoth\u00e9rapeute sans avoir besoin d\u2019une r\u00e9f\u00e9rence m\u00e9dicale.<\/p>\n<p>Dans l\u2019approche de consultation unique, le th\u00e9rapeute mise sur les forces de la personne pour l\u2019aider \u00e0 g\u00e9rer une situation difficile. Dans la plupart des cas, une seule consultation est suffisante pour lui permettre de prendre la situation en main et de cheminer dans la direction o\u00f9 elle souhaite aller. \u00c0 la fin de la consultation, si le th\u00e9rapeute et la personne sentent qu\u2019il y a un besoin pour une th\u00e9rapie \u00e0 plus long terme, nous pouvons la r\u00e9f\u00e9rer \u00e0 un autre programme.<\/p>\n<p>Les personnes qui vivent une situation difficile et qui souhaitent en parler \u00e0 quelqu\u2019un sans crainte de jugement peuvent venir \u00e0 la clinique ou t\u00e9l\u00e9phoner pour b\u00e9n\u00e9ficier d\u2019une consultation unique. Les personnes peuvent aborder toutes sortes de questions comme les conflits familiaux ou de couple, une s\u00e9paration, un deuil, le stress li\u00e9 au travail, la d\u00e9pression, l\u2019anxi\u00e9t\u00e9, les d\u00e9pendances, l\u2019identit\u00e9 sexuelle, une agression sexuelle, ou autre situation difficile.<\/p>\n<p>La clinique sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale et toxicomanie situ\u00e9 au 580, avenue Spence \u00e0 Hawkesbury. Pour une consultation par t\u00e9l\u00e9phone, il faut composer le 1-844-304-1414, option 2.<\/p>\n<p>La clinique sera ferm\u00e9e le mercredi 30 d\u00e9cembre 2020.<\/p>\n<p>Pour plus d\u2019information, visitez la page <a href=\"https:\/\/hgh.ca\/fr\/programmes-services\/clinique-de-counseling-sans-rendez-vous-consultation-unique\/\">Clinique de counseling sans rendez-vous<\/a>.\u00a0Pour de l\u2019information sur les autres programmes et services, visitez la page <a href=\"https:\/\/hgh.ca\/fr\/sante-mentale-et-toxicomanie\/\">Sant\u00e9 mentale et toxicomanie<\/a>.<\/p>\n<p>La Clinique de counseling sans rendez-vous a \u00e9t\u00e9 mise sur pied gr\u00e2ce au soutien financier de <a href=\"https:\/\/cause.bell.ca\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bell Cause pour la cause<\/a> et de la <a href=\"https:\/\/hgh.ca\/foundation\/fr\/\">Fondation HGH<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6829 size-large\" src=\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous-700x472.jpg\" alt=\"&quot; &quot;\" width=\"700\" height=\"472\" srcset=\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous-700x472.jpg 700w, https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous-250x168.jpg 250w, https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous-768x517.jpg 768w, https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous-120x81.jpg 120w, https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/Nouvelle-clinique-sans-rendez-vous.jpg 803w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"Le d\u00e9partement de Sant\u00e9 mentale et toxicomanie de l\u2019HGH offre maintenant un acc\u00e8s simple et rapide \u00e0 des services de counseling sans rendez-vous. Les personnes \u00e2g\u00e9es de 16 ans ou plus peuvent obtenir une consultation unique avec un psychoth\u00e9rapeute sans avoir besoin d\u2019une r\u00e9f\u00e9rence m\u00e9dicale. Dans l\u2019approche de consultation unique, le th\u00e9rapeute mise sur les&#8230; <a class=\"btn btn--primary\" href=\"https:\/\/hgh.ca\/fr\/nouvelle-clinique-de-counseling-sans-rendez-vous\/\">Acc\u00e9der l&rsquo;article<\/a>","protected":false},"author":2,"featured_media":6827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[184,183,185],"class_list":["post-6832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-bell-cause-pour-la-cause","tag-clinique-counseling-sans-rendez-vous","tag-fondation-hgh"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital<\/title>\n<meta name=\"description\" content=\"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hgh.ca\/fr\/new-walk-in-counselling-clinic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital\" \/>\n<meta property=\"og:description\" content=\"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/\" \/>\n<meta property=\"og:site_name\" content=\"Hawkesbury General Hospital\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-23T14:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-14T19:43:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julie Leroux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julie Leroux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/\",\"url\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/\",\"name\":\"Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital\",\"isPartOf\":{\"@id\":\"https:\/\/hgh.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg\",\"datePublished\":\"2020-11-23T14:19:03+00:00\",\"dateModified\":\"2020-12-14T19:43:15+00:00\",\"author\":{\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\"},\"description\":\"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.\",\"breadcrumb\":{\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage\",\"url\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg\",\"contentUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg\",\"width\":300,\"height\":250,\"caption\":\"\\\" \\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hgh.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelle clinique de counseling sans rendez-vous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hgh.ca\/#website\",\"url\":\"https:\/\/hgh.ca\/\",\"name\":\"Hawkesbury General Hospital\",\"description\":\"Compassion, Innovation, Excellence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hgh.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\",\"name\":\"Julie Leroux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"caption\":\"Julie Leroux\"},\"url\":\"https:\/\/hgh.ca\/fr\/author\/jleroux\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital","description":"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hgh.ca\/fr\/new-walk-in-counselling-clinic\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital","og_description":"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.","og_url":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/","og_site_name":"Hawkesbury General Hospital","article_published_time":"2020-11-23T14:19:03+00:00","article_modified_time":"2020-12-14T19:43:15+00:00","og_image":[{"width":300,"height":250,"url":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg","type":"image\/jpeg"}],"author":"Julie Leroux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julie Leroux","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/","url":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/","name":"Nouvelle clinique de counseling sans rendez-vous - Hawkesbury General Hospital","isPartOf":{"@id":"https:\/\/hgh.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage"},"image":{"@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage"},"thumbnailUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg","datePublished":"2020-11-23T14:19:03+00:00","dateModified":"2020-12-14T19:43:15+00:00","author":{"@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4"},"description":"La Clinique de counseling sans rendez-vous est offerte les mercredis de 9 h \u00e0 15 h au Centre r\u00e9gional de sant\u00e9 mentale \u00e0 Hawkesbury.","breadcrumb":{"@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#primaryimage","url":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg","contentUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/11\/walk-in-clinic-300.jpg","width":300,"height":250,"caption":"\" \""},{"@type":"BreadcrumbList","@id":"https:\/\/hgh.ca\/new-walk-in-counselling-clinic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hgh.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelle clinique de counseling sans rendez-vous"}]},{"@type":"WebSite","@id":"https:\/\/hgh.ca\/#website","url":"https:\/\/hgh.ca\/","name":"Hawkesbury General Hospital","description":"Compassion, Innovation, Excellence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hgh.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4","name":"Julie Leroux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","caption":"Julie Leroux"},"url":"https:\/\/hgh.ca\/fr\/author\/jleroux\/"}]}},"_links":{"self":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/6832\/"}],"collection":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/users\/2\/"}],"replies":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/comments\/?post=6832"}],"version-history":[{"count":2,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/6832\/revisions\/"}],"predecessor-version":[{"id":6916,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/6832\/revisions\/6916\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/6827\/"}],"wp:attachment":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/?parent=6832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/categories\/?post=6832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/tags\/?post=6832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}