{"id":9480,"date":"2023-10-06T16:48:17","date_gmt":"2023-10-06T20:48:17","guid":{"rendered":"https:\/\/hgh.ca\/?p=9480"},"modified":"2023-10-06T16:48:17","modified_gmt":"2023-10-06T20:48:17","slug":"eclosion-declaree-a-lhgh-le-6-octobre-2023","status":"publish","type":"post","link":"https:\/\/hgh.ca\/fr\/eclosion-declaree-a-lhgh-le-6-octobre-2023\/","title":{"rendered":"\u00c9closion d\u00e9clar\u00e9e \u00e0 l&rsquo;HGH le 6 octobre 2023"},"content":{"rendered":"<p>Aujourd&rsquo;hui, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) a d\u00e9clar\u00e9 une \u00e9closion de COVID-19 dans deux de ses unit\u00e9s d\u2019hospitalisation. La priorit\u00e9 de l\u2019HGH continue d\u2019\u00eatre la s\u00e9curit\u00e9 de nos patients et de leurs familles, de nos employ\u00e9s et de nos m\u00e9decins, ainsi que de notre communaut\u00e9.<\/p>\n<p>Nous poursuivons avec diligence nos efforts pour contenir et g\u00e9rer la situation. Nos professionnels de la sant\u00e9 d\u00e9vou\u00e9s suivent tous les protocoles recommand\u00e9s et des mesures suppl\u00e9mentaires sont mises en place. Ces mesures sont les suivantes :<\/p>\n<ul>\n<li>Fermeture de l\u2019unit\u00e9 \u00e0 toute nouvelle admission.<\/li>\n<li>Renforcement du nettoyage de l\u2019unit\u00e9, y compris de toutes les zones communes de l\u2019unit\u00e9.<\/li>\n<\/ul>\n<p>Gr\u00e2ce \u00e0 notre b\u00e2timent et nos infrastructures modernes, l\u2019HGH dispose de zones de services distinctes qui limitent les mouvements entre les secteurs am\u00e9liorant ainsi la s\u00e9curit\u00e9 et limitant la propagation du virus. Le service d\u2019urgence, l\u2019imagerie m\u00e9dicale, les cliniques ambulatoires, le centre familial de naissances et la chirurgie d\u2019un jour demeurent ouverts. Les patients peuvent acc\u00e9der \u00e0 ces zones et recevoir des soins en toute s\u00e9curit\u00e9.<\/p>\n<p>Tous les visiteurs doivent porter un masque en tout temps dans l\u2019h\u00f4pital. Des masques sont fournis.<\/p>\n<p>Il est attendu que chacun adopte une bonne hygi\u00e8ne des mains en utilisant les d\u00e9sinfectants pour les mains r\u00e9partis dans l\u2019\u00e9tablissement et en se lavant les mains r\u00e9guli\u00e8rement.<\/p>\n<p>Afin de minimiser le risque de transmission de maladies infectieuses, les restrictions suivantes concernant les visiteurs seront mises en place d\u00e8s maintenant :<\/p>\n<ul>\n<li>Seuls les visiteurs essentiels seront autoris\u00e9s \u00e0 rendre visite \u00e0 un patient Covid-19 positif.<\/li>\n<li>Visiteurs :\u00a0 Si vous ne vous sentez pas bien, si vous avez des sympt\u00f4mes grippaux ou de la fi\u00e8vre, nous vous demandons de reporter votre visite.<\/li>\n<\/ul>\n<p>Nous invitons les membres de la communaut\u00e9 \u00e0 suivre toutes les recommandations de sant\u00e9 publique, notamment \u00e0 se faire vacciner, \u00e0 pratiquer une bonne hygi\u00e8ne des mains et \u00e0 porter un masque dans les espaces publics afin de r\u00e9duire la propagation des maladies infectieuses.<\/p>\n<p>HGH demeure engag\u00e9 envers la sant\u00e9 et le bien-\u00eatre de ses patients, de ses employ\u00e9s, ses m\u00e9decins et de sa communaut\u00e9. Nous vous remercions de votre compr\u00e9hension et de votre coop\u00e9ration.<\/p>\n","protected":false},"excerpt":{"rendered":"Aujourd&rsquo;hui, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) a d\u00e9clar\u00e9 une \u00e9closion de COVID-19 dans deux de ses unit\u00e9s d\u2019hospitalisation. La priorit\u00e9 de l\u2019HGH continue d\u2019\u00eatre la s\u00e9curit\u00e9 de nos patients et de leurs familles, de nos employ\u00e9s et de nos m\u00e9decins, ainsi que de notre communaut\u00e9. Nous poursuivons avec diligence nos efforts pour contenir&#8230; <a class=\"btn btn--primary\" href=\"https:\/\/hgh.ca\/fr\/eclosion-declaree-a-lhgh-le-6-octobre-2023\/\">Acc\u00e9der l&rsquo;article<\/a>","protected":false},"author":2,"featured_media":5964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-9480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9closion d\u00e9clar\u00e9e \u00e0 l&#039;HGH le 6 octobre 2023 - Hawkesbury General Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hgh.ca\/fr\/outbreak-declared-at-hgh-on-october-6-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9closion d\u00e9clar\u00e9e \u00e0 l&#039;HGH le 6 octobre 2023 - Hawkesbury General Hospital\" \/>\n<meta property=\"og:description\" content=\"Aujourd&rsquo;hui, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) a d\u00e9clar\u00e9 une \u00e9closion de COVID-19 dans deux de ses unit\u00e9s d\u2019hospitalisation. La priorit\u00e9 de l\u2019HGH continue d\u2019\u00eatre la s\u00e9curit\u00e9 de nos patients et de leurs familles, de nos employ\u00e9s et de nos m\u00e9decins, ainsi que de notre communaut\u00e9. Nous poursuivons avec diligence nos efforts pour contenir... Acc\u00e9der l&#039;article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Hawkesbury General Hospital\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-06T20:48:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julie Leroux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julie Leroux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/\",\"url\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/\",\"name\":\"\u00c9closion d\u00e9clar\u00e9e \u00e0 l'HGH le 6 octobre 2023 - Hawkesbury General Hospital\",\"isPartOf\":{\"@id\":\"https:\/\/hgh.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png\",\"datePublished\":\"2023-10-06T20:48:17+00:00\",\"dateModified\":\"2023-10-06T20:48:17+00:00\",\"author\":{\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage\",\"url\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png\",\"contentUrl\":\"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png\",\"width\":300,\"height\":250,\"caption\":\"pr\u00e9vention des infections\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hgh.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9closion d\u00e9clar\u00e9e \u00e0 l&#8217;HGH le 6 octobre 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hgh.ca\/#website\",\"url\":\"https:\/\/hgh.ca\/\",\"name\":\"Hawkesbury General Hospital\",\"description\":\"Compassion, Innovation, Excellence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hgh.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4\",\"name\":\"Julie Leroux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hgh.ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g\",\"caption\":\"Julie Leroux\"},\"url\":\"https:\/\/hgh.ca\/fr\/author\/jleroux\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9closion d\u00e9clar\u00e9e \u00e0 l'HGH le 6 octobre 2023 - Hawkesbury General Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hgh.ca\/fr\/outbreak-declared-at-hgh-on-october-6-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9closion d\u00e9clar\u00e9e \u00e0 l'HGH le 6 octobre 2023 - Hawkesbury General Hospital","og_description":"Aujourd&rsquo;hui, l\u2019H\u00f4pital g\u00e9n\u00e9ral de Hawkesbury et district (HGH) a d\u00e9clar\u00e9 une \u00e9closion de COVID-19 dans deux de ses unit\u00e9s d\u2019hospitalisation. La priorit\u00e9 de l\u2019HGH continue d\u2019\u00eatre la s\u00e9curit\u00e9 de nos patients et de leurs familles, de nos employ\u00e9s et de nos m\u00e9decins, ainsi que de notre communaut\u00e9. Nous poursuivons avec diligence nos efforts pour contenir... Acc\u00e9der l'article","og_url":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/","og_site_name":"Hawkesbury General Hospital","article_published_time":"2023-10-06T20:48:17+00:00","og_image":[{"width":300,"height":250,"url":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png","type":"image\/png"}],"author":"Julie Leroux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julie Leroux","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/","url":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/","name":"\u00c9closion d\u00e9clar\u00e9e \u00e0 l'HGH le 6 octobre 2023 - Hawkesbury General Hospital","isPartOf":{"@id":"https:\/\/hgh.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage"},"image":{"@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png","datePublished":"2023-10-06T20:48:17+00:00","dateModified":"2023-10-06T20:48:17+00:00","author":{"@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4"},"breadcrumb":{"@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#primaryimage","url":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png","contentUrl":"https:\/\/hgh.ca\/wp-content\/uploads\/2020\/03\/virus-300.png","width":300,"height":250,"caption":"pr\u00e9vention des infections"},{"@type":"BreadcrumbList","@id":"https:\/\/hgh.ca\/outbreak-declared-at-hgh-on-october-6-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hgh.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9closion d\u00e9clar\u00e9e \u00e0 l&#8217;HGH le 6 octobre 2023"}]},{"@type":"WebSite","@id":"https:\/\/hgh.ca\/#website","url":"https:\/\/hgh.ca\/","name":"Hawkesbury General Hospital","description":"Compassion, Innovation, Excellence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hgh.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/hgh.ca\/#\/schema\/person\/b4390eb1b4836367e1e66acd0c0046d4","name":"Julie Leroux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hgh.ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e08690de5275dd5cab54576427bf18d4?s=96&d=mm&r=g","caption":"Julie Leroux"},"url":"https:\/\/hgh.ca\/fr\/author\/jleroux\/"}]}},"_links":{"self":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/9480\/"}],"collection":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/users\/2\/"}],"replies":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/comments\/?post=9480"}],"version-history":[{"count":2,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/9480\/revisions\/"}],"predecessor-version":[{"id":9485,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/posts\/9480\/revisions\/9485\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/5964\/"}],"wp:attachment":[{"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/media\/?parent=9480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/categories\/?post=9480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hgh.ca\/fr\/wp-json\/wp\/v2\/tags\/?post=9480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}